{"id":11,"count":3,"description":"","link":"http:\/\/michaelbielaczyc.com\/blog\/tag\/costumes\/","name":"costumes","slug":"costumes","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/michaelbielaczyc.com\/blog\/wp-json\/wp\/v2\/tags\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/michaelbielaczyc.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/michaelbielaczyc.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/michaelbielaczyc.com\/blog\/wp-json\/wp\/v2\/posts?tags=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}